{"id":507,"count":0,"description":"","link":"https:\/\/www.lathiau.fr\/en\/tag\/ecluses-en\/","name":"\u00e9cluses","slug":"ecluses-en","taxonomy":"post_tag","meta":[],"yoast_head":"\n<title>\u00e9cluses Archives - Chambres d&#039;h\u00f4tes de charme, g\u00eetes Loiret Briare Gien Sancerre<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00e9cluses Archives - Chambres d&#039;h\u00f4tes de charme, g\u00eetes Loiret Briare Gien Sancerre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lathiau.fr\/en\/tag\/ecluses-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Chambres d&#039;h\u00f4tes de charme, g\u00eetes Loiret Briare Gien Sancerre\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lathiau.fr\/wp-content\/uploads\/2014\/04\/alleeprunus1wp.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lathiau.fr\/#website\",\"url\":\"https:\/\/www.lathiau.fr\/\",\"name\":\"Chambres d&#039;h\\u00f4tes de charme, g\\u00eetes Loiret Briare Gien Sancerre\",\"description\":\"Chambres d&#039;h\\u00f4tes de charme et g\\u00eetes en Val de Loire entre Gien et Briare Sancerre Loiret 150km sud de Paris. Maison ind\\u00e9pendante, parc paysager, diner romantique, chateaux.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.lathiau.fr\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.lathiau.fr\/en\/tag\/ecluses-en\/#webpage\",\"url\":\"https:\/\/www.lathiau.fr\/en\/tag\/ecluses-en\/\",\"name\":\"\\u00e9cluses Archives - Chambres d&#039;h\\u00f4tes de charme, g\\u00eetes Loiret Briare Gien Sancerre\",\"isPartOf\":{\"@id\":\"https:\/\/www.lathiau.fr\/#website\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lathiau.fr\/en\/tag\/ecluses-en\/\"]}]}]}<\/script>\n","_links":{"self":[{"href":"https:\/\/www.lathiau.fr\/en\/wp-json\/wp\/v2\/tags\/507\/"}],"collection":[{"href":"https:\/\/www.lathiau.fr\/en\/wp-json\/wp\/v2\/tags\/"}],"about":[{"href":"https:\/\/www.lathiau.fr\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag\/"}],"wp:post_type":[{"href":"https:\/\/www.lathiau.fr\/en\/wp-json\/wp\/v2\/posts\/?tags=507"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}